{"id":302,"count":1,"description":"","link":"https:\/\/zelina.mx\/en\/product-category\/boxer-en\/","name":"Boxer","slug":"boxer-en","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boxer Archives - Zelina Lingerie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zelina.mx\/en\/product-category\/boxer-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boxer Archives - Zelina Lingerie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zelina.mx\/en\/product-category\/boxer-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Zelina Lingerie\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zelina.mx\/wp-content\/uploads\/2019\/06\/Zelina.Editorial-25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zelina.mx\\\/categoria-producto\\\/boxer-en\\\/\",\"url\":\"https:\\\/\\\/zelina.mx\\\/categoria-producto\\\/boxer-en\\\/\",\"name\":\"Boxer Archives - Zelina Lingerie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zelina.mx\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zelina.mx\\\/categoria-producto\\\/boxer-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zelina.mx\\\/categoria-producto\\\/boxer-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/zelina.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boxer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zelina.mx\\\/#website\",\"url\":\"https:\\\/\\\/zelina.mx\\\/\",\"name\":\"Zelina Lingerie\",\"description\":\"El espacio donde ser sexy es un estilo de vida\",\"publisher\":{\"@id\":\"https:\\\/\\\/zelina.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zelina.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zelina.mx\\\/#organization\",\"name\":\"Zelina Lingerie\",\"url\":\"https:\\\/\\\/zelina.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zelina.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zelina.mx\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cropped-cropped-cropped-cropped-Zelina-logos-G.png\",\"contentUrl\":\"https:\\\/\\\/zelina.mx\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cropped-cropped-cropped-cropped-Zelina-logos-G.png\",\"width\":199,\"height\":80,\"caption\":\"Zelina Lingerie\"},\"image\":{\"@id\":\"https:\\\/\\\/zelina.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Secrets.by.Zelina\\\/\",\"https:\\\/\\\/www.instagram.com\\\/secretsbyzelina\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boxer Archives - Zelina Lingerie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zelina.mx\/en\/product-category\/boxer-en\/","og_locale":"en_US","og_type":"article","og_title":"Boxer Archives - Zelina Lingerie","og_url":"https:\/\/zelina.mx\/en\/product-category\/boxer-en\/","og_site_name":"Zelina Lingerie","og_image":[{"width":2400,"height":1600,"url":"https:\/\/zelina.mx\/wp-content\/uploads\/2019\/06\/Zelina.Editorial-25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zelina.mx\/categoria-producto\/boxer-en\/","url":"https:\/\/zelina.mx\/categoria-producto\/boxer-en\/","name":"Boxer Archives - Zelina Lingerie","isPartOf":{"@id":"https:\/\/zelina.mx\/#website"},"breadcrumb":{"@id":"https:\/\/zelina.mx\/categoria-producto\/boxer-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/zelina.mx\/categoria-producto\/boxer-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/zelina.mx\/"},{"@type":"ListItem","position":2,"name":"Boxer"}]},{"@type":"WebSite","@id":"https:\/\/zelina.mx\/#website","url":"https:\/\/zelina.mx\/","name":"Zelina Lingerie","description":"El espacio donde ser sexy es un estilo de vida","publisher":{"@id":"https:\/\/zelina.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zelina.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zelina.mx\/#organization","name":"Zelina Lingerie","url":"https:\/\/zelina.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zelina.mx\/#\/schema\/logo\/image\/","url":"https:\/\/zelina.mx\/wp-content\/uploads\/2019\/11\/cropped-cropped-cropped-cropped-Zelina-logos-G.png","contentUrl":"https:\/\/zelina.mx\/wp-content\/uploads\/2019\/11\/cropped-cropped-cropped-cropped-Zelina-logos-G.png","width":199,"height":80,"caption":"Zelina Lingerie"},"image":{"@id":"https:\/\/zelina.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Secrets.by.Zelina\/","https:\/\/www.instagram.com\/secretsbyzelina\/"]}]}},"_links":{"self":[{"href":"https:\/\/zelina.mx\/en\/wp-json\/wp\/v2\/product_cat\/302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zelina.mx\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/zelina.mx\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/zelina.mx\/en\/wp-json\/wp\/v2\/product?product_cat=302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}